{"id":9771,"date":"2023-03-03T08:33:45","date_gmt":"2023-03-03T11:33:45","guid":{"rendered":"https:\/\/alcantara.pro.br\/portal\/?p=9771"},"modified":"2023-09-25T21:56:22","modified_gmt":"2023-09-25T21:56:22","slug":"e-book-contabilidade-para-microentidades-nbc-tg-1002","status":"publish","type":"post","link":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/","title":{"rendered":"e-Book: Contabilidade para Microentidades (NBC TG 1002)"},"content":{"rendered":"<p>A partir de janeiro de 2023 entrou em vigor a NBC TG 1002, expedida pela Conselho Federal de Contabilidade dispondo sobre a contabilidade para microentidades.<\/p>\n<p>O Prof. Antonio Carlos Ribeiro (ACR), um dos maiores especialistas no Brasil sobre contabilidade de pequenas e m\u00e9dias empresas la\u00e7ou um excelente livro em formato digital sobre as novidades trazidas sobre esta nova norma do CFC, destinada especificamente para a escritura\u00e7\u00e3o cont\u00e1bil das microentidades, com v\u00e1rios exemplos pr\u00e1ticos.<\/p>\n<p>O lan\u00e7amento est\u00e1 dispon\u00edvel para aquisi\u00e7\u00e3o na p\u00e1gina do autor, e compreende:<\/p>\n<ul>\n<li>Livro Digital Demonstra\u00e7\u00f5es Cont\u00e1beis para Microentidades e Pequenas Empresas<\/li>\n<li>Livro Digital Modelo de Plano de Contas comentado (b\u00f4nus)<\/li>\n<li>Curso online de Contabilidade para Microentidades (b\u00f4nus)<\/li>\n<\/ul>\n<p>Confira <a href=\"https:\/\/profacr.com.br\/ebook\/\" target=\"_blank\" rel=\"noopener\"><strong>aqui<\/strong> <\/a>e adquira, <em><strong>eu comprei e gostei demais<\/strong><\/em>, recomendo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de janeiro de 2023 entrou em vigor a NBC TG 1002, expedida pela<\/p>\n","protected":false},"author":1,"featured_media":10574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,135,88,150],"tags":[],"class_list":["post-9771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cfc","category-livros","category-escrituracao-contabil","category-normas-contabeis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara\" \/>\n<meta property=\"og:description\" content=\"A partir de janeiro de 2023 entrou em vigor a NBC TG 1002, expedida pela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/\" \/>\n<meta property=\"og:site_name\" content=\"Prof. Alexandre Alcantara\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T11:33:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-25T21:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Editoria: Prof. Alexandre Alcantara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria: Prof. Alexandre Alcantara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/\"},\"author\":{\"name\":\"Editoria: Prof. Alexandre Alcantara\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/1991ac6c2adfbaedfb22ff57aed2c7db\"},\"headline\":\"e-Book: Contabilidade para Microentidades (NBC TG 1002)\",\"datePublished\":\"2023-03-03T11:33:45+00:00\",\"dateModified\":\"2023-09-25T21:56:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\"},\"image\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/banner-dica-de-livros.png\",\"articleSection\":[\"CFC\",\"Dicas de Livros\",\"Escritura\u00e7\u00e3o Cont\u00e1bil\",\"Normas Cont\u00e1beis\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/\",\"name\":\"e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/banner-dica-de-livros.png\",\"datePublished\":\"2023-03-03T11:33:45+00:00\",\"dateModified\":\"2023-09-25T21:56:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/banner-dica-de-livros.png\",\"contentUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/banner-dica-de-livros.png\",\"width\":760,\"height\":257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2023\\\/03\\\/03\\\/e-book-contabilidade-para-microentidades-nbc-tg-1002\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"e-Book: Contabilidade para Microentidades (NBC TG 1002)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/\",\"name\":\"Prof. Alexandre Alcantara\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\",\"name\":\"Alexandre Alcantara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"contentUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"width\":512,\"height\":512,\"caption\":\"Alexandre Alcantara\"},\"logo\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/1991ac6c2adfbaedfb22ff57aed2c7db\",\"name\":\"Editoria: Prof. Alexandre Alcantara\",\"sameAs\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\"],\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/author\\\/alexandreportal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/","og_locale":"pt_BR","og_type":"article","og_title":"e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara","og_description":"A partir de janeiro de 2023 entrou em vigor a NBC TG 1002, expedida pela","og_url":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/","og_site_name":"Prof. Alexandre Alcantara","article_published_time":"2023-03-03T11:33:45+00:00","article_modified_time":"2023-09-25T21:56:22+00:00","og_image":[{"width":760,"height":257,"url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png","type":"image\/png"}],"author":"Editoria: Prof. Alexandre Alcantara","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editoria: Prof. Alexandre Alcantara","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#article","isPartOf":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/"},"author":{"name":"Editoria: Prof. Alexandre Alcantara","@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/1991ac6c2adfbaedfb22ff57aed2c7db"},"headline":"e-Book: Contabilidade para Microentidades (NBC TG 1002)","datePublished":"2023-03-03T11:33:45+00:00","dateModified":"2023-09-25T21:56:22+00:00","mainEntityOfPage":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975"},"image":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#primaryimage"},"thumbnailUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png","articleSection":["CFC","Dicas de Livros","Escritura\u00e7\u00e3o Cont\u00e1bil","Normas Cont\u00e1beis"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/","url":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/","name":"e-Book: Contabilidade para Microentidades (NBC TG 1002) - Prof. Alexandre Alcantara","isPartOf":{"@id":"https:\/\/alcantara.pro.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#primaryimage"},"image":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#primaryimage"},"thumbnailUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png","datePublished":"2023-03-03T11:33:45+00:00","dateModified":"2023-09-25T21:56:22+00:00","breadcrumb":{"@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#primaryimage","url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png","contentUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2023\/03\/banner-dica-de-livros.png","width":760,"height":257},{"@type":"BreadcrumbList","@id":"https:\/\/alcantara.pro.br\/portal\/2023\/03\/03\/e-book-contabilidade-para-microentidades-nbc-tg-1002\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/alcantara.pro.br\/portal\/"},{"@type":"ListItem","position":2,"name":"e-Book: Contabilidade para Microentidades (NBC TG 1002)"}]},{"@type":"WebSite","@id":"https:\/\/alcantara.pro.br\/portal\/#website","url":"https:\/\/alcantara.pro.br\/portal\/","name":"Prof. Alexandre Alcantara","description":"","publisher":{"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcantara.pro.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975","name":"Alexandre Alcantara","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","contentUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","width":512,"height":512,"caption":"Alexandre Alcantara"},"logo":{"@id":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png"}},{"@type":"Person","@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/1991ac6c2adfbaedfb22ff57aed2c7db","name":"Editoria: Prof. Alexandre Alcantara","sameAs":["https:\/\/alcantara.pro.br\/portal"],"url":"https:\/\/alcantara.pro.br\/portal\/author\/alexandreportal\/"}]}},"_links":{"self":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/9771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/comments?post=9771"}],"version-history":[{"count":1,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/9771\/revisions"}],"predecessor-version":[{"id":10575,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/9771\/revisions\/10575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/media\/10574"}],"wp:attachment":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/media?parent=9771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/categories?post=9771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/tags?post=9771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}