{"id":8861,"date":"2015-10-24T18:00:01","date_gmt":"2015-10-24T21:00:01","guid":{"rendered":"https:\/\/alcantara.pro.br\/portal\/?p=8861"},"modified":"2023-09-28T16:44:20","modified_gmt":"2023-09-28T16:44:20","slug":"x-enat-aborda-conversao-de-dados-em-conhecimento","status":"publish","type":"post","link":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/","title":{"rendered":"X Enat aborda convers\u00e3o de dados em conhecimento"},"content":{"rendered":"<p>Ser\u00e1 firmado protocolo para distribui\u00e7\u00e3o de vers\u00e3o de ferramenta de Business Intelligence da Receita Federal, o <strong><span style=\"background-color: #ffff00;\">Cont\u00c1gil Lite<\/span><\/strong>, \u00e0s Secretarias de Fazendas e de Finan\u00e7as.<\/p>\n<p>Business Intelligence (BI) \u00e9 a capacidade que a organiza\u00e7\u00e3o possui de extrair conhecimento de seus dados. O assunto foi tema de painel do terceiro dia de atividades do X Encontro Nacional de Administradores Tribut\u00e1rios (Enat).<\/p>\n<p>\u201cEsse \u00e9 um tema bastante inovador\u201d, disse Cl\u00e1udio Vasconcelos Braga, auditor-fiscal da Coordena\u00e7\u00e3o-Geral de Tecnologia da Informa\u00e7\u00e3o (Cotec) e gerente do projeto de Minera\u00e7\u00e3o de Dados da Receita Federal. \u201cAs tecnologias tradicionais n\u00e3o s\u00e3o capazes de prover um processamento t\u00e3o r\u00e1pido quanto necess\u00e1rio. Por isso, nos \u00faltimos anos, surgiram modernas tecnologias, tanto de software quanto de hardware, que conseguem prover um processamento muito mais r\u00e1pido e eficaz\u201d, apontou.<\/p>\n<p>Braga discorreu sobre a arquitetura de refer\u00eancia BI dentro da Receita Federal e sobre as capacidades anal\u00edticas que est\u00e3o sendo implementadas dentro do \u00d3rg\u00e3o. \u201cNa Receita, os dados s\u00e3o extra\u00eddos dos sistemas fonte e tamb\u00e9m do Sped (Sistema P\u00fablico e Escritura\u00e7\u00e3o Digital), passam por um processo de valida\u00e7\u00e3o, transforma\u00e7\u00e3o e integra\u00e7\u00e3o e s\u00e3o carregados em um grande banco de dados. A partir da\u00ed, diversas ferramentas podem acessar esse conjunto de dados e extrair conhecimento\u201d, explicou, enfatizando a multiplicidade de ferramentas de extra\u00e7\u00e3o \u00e0 disposi\u00e7\u00e3o dos usu\u00e1rios. O self-service \u00e9 uma das premissas. \u201cO usu\u00e1rio, usando as ferramentas BI, obt\u00e9m o conhecimento que ele acha necess\u00e1rio sem interven\u00e7\u00e3o direta da \u00e1rea de tecnologia\u201d, disse.<\/p>\n<p>O auditor-fiscal falou ainda das quatro capacidades anal\u00edticas que est\u00e3o sendo desenvolvidas no \u00e2mbito da Receita Federal e ajudam a responder perguntas-chave: descritiva (o que aconteceu?), diagn\u00f3stica (por que isso aconteceu?), preditiva (o que vai acontecer?) e de direcionamento (o que eu devo fazer?). Exemplos de ferramentas que utilizam as capacidades s\u00e3o dashboards; aplicativos Online Analytical Processing (Olap) e Data Discovery; MicroStrategy, <span style=\"background-color: #ffff00;\"><strong>Cont\u00c1gil<\/strong> <\/span>e ferramentas de Minera\u00e7\u00e3o de Dados (como a SAS).<\/p>\n<p>Na \u00e1rea de minera\u00e7\u00e3o de dados, Braga citou o exemplo de um projeto piloto focado no Imposto de Renda Pessoa F\u00edsica (IRPF). \u201cNesse projeto, foram identificados dez escrit\u00f3rios de contabilidade especializados em fazer declara\u00e7\u00f5es do IRPF com isen\u00e7\u00e3o indevida do imposto. Os valores das restitui\u00e7\u00f5es foram superiores a R$ 12 milh\u00f5es\u201d, contou.<\/p>\n<p>Felippe Aquino de Moura, chefe da Divis\u00e3o de Projetos Estrat\u00e9gicos da Fiscaliza\u00e7\u00e3o da Receita Federal e gestor do <strong><span style=\"background-color: #ffff00;\">Cont\u00c1gil<\/span><\/strong>, fez uma apresenta\u00e7\u00e3o sobre o sistema desenvolvido internamente na Receita Federal. Trata-se de um sistema que oferece ferramentas para que o usu\u00e1rio trabalhe com os mais diversos dados. Iniciado em 2007, pelo auditor-fiscal Gustavo Figueiredo, o <strong><span style=\"background-color: #ffff00;\">Cont\u00c1gil<\/span><\/strong> \u00e9 um aplicativo desktop baseado em software live. \u201cO <span style=\"background-color: #ffff00;\"><strong>Cont\u00c1gil<\/strong><\/span> surgiu como um visualizador gr\u00e1fico de fluxos cont\u00e1beis\u201d, disse Moura, que acrescentou que os aprimoramentos do sistema v\u00eam sendo feitos paulatinamente com a colabora\u00e7\u00e3o dos usu\u00e1rios. Hoje, o sistema j\u00e1 possui 273 funcionalidades.<\/p>\n<p>A ferramenta foi pensada e customizada para uso na Receita Federal. \u201cPor conta do sucesso, foi surgindo o interesse das Secretarias de Fazenda e de Finan\u00e7as de utilizar o <span style=\"background-color: #ffff00;\"><strong>Cont\u00c1gil<\/strong><\/span> e a Receita Federal assumiu o compromisso de gerar uma vers\u00e3o do sistema para uso dessas secretarias: o <span style=\"background-color: #ffff00;\"><strong>Cont\u00c1gil<\/strong> <\/span>Lite\u201d, disse Moura. Trata-se de uma vers\u00e3o com as principais funcionalidades gen\u00e9ricas da ferramenta, tais como importa\u00e7\u00e3o de arquivos espec\u00edficos e gen\u00e9ricos; visualiza\u00e7\u00e3o gr\u00e1fica da contabilidade dos contribuintes; Modelo Anal\u00edtico Din\u00e2mico com mais de 170 f\u00f3rmulas; explora\u00e7\u00e3o de gr\u00e1ficos; minera\u00e7\u00e3o de dados e scripts. \u201c\u00c9 atrav\u00e9s desses scripts que cada Secretaria vai poder criar suas pr\u00f3prias regras de neg\u00f3cios, com seus pr\u00f3prios batimentos\u201d, salientou o palestrante. Ser\u00e1 firmado um protocolo para distribui\u00e7\u00e3o desse sistema \u00e0s Secretarias.<\/p>\n<p>O \u00faltimo palestrante do painel foi Cl\u00e1udio Roberto Alves Ferreira, agente-fiscal de rendas da Secretaria da Fazenda do Estado de S\u00e3o Paulo (Sefaz\/SP), que discorreu sobre o ambiente BI no \u00d3rg\u00e3o, abordando a infraestrutura, as ferramentas utilizadas e os exemplos de minera\u00e7\u00e3o de dados. O BI j\u00e1 est\u00e1 instalado na Sefaz\/SP h\u00e1 cerca de dez anos. Hoje, existem tr\u00eas ferramentas principais \u00e0 disposi\u00e7\u00e3o. \u201cAs pr\u00f3prias \u00e1reas de neg\u00f3cios montam seus dashboards, suas an\u00e1lises. Qual ferramenta vai ser usada fica a crit\u00e9rio do usu\u00e1rio final\u201d, explicou Ferreira.<\/p>\n<p>O Data Warehouse permite a constru\u00e7\u00e3o e execu\u00e7\u00e3o de relat\u00f3rios e gr\u00e1ficos. J\u00e1 a ferramenta de an\u00e1lise visual permite a visualiza\u00e7\u00e3o dos dados de maneira gr\u00e1fica e interativa. Por fim, a ferramenta de an\u00e1lise estat\u00edstica permite a constru\u00e7\u00e3o de modelos para descobrir padr\u00f5es e tend\u00eancias. Um exemplo de minera\u00e7\u00e3o de dados apontado por Ferreira foi a Opera\u00e7\u00e3o Quebra -Gelo, iniciada em 2012, e que teve como foco identificar e fechar empresas que faziam emiss\u00e3o irregular de notas fiscais. \u201cUtilizando a sele\u00e7\u00e3o a partir da ferramenta, n\u00f3s conseguimos uma assertividade de 80%\u201d, contou.<\/p>\n<p>A delegada da Delegacia Especial de Maiores Contribuintes (Demac) da Receita Federal em S\u00e3o Paulo, M\u00e1rcia Cec\u00edlia Meng, foi a moderadora do painel. \u201cOs dados s\u00e3o a base do nosso trabalho. Mas, muitas vezes, para quem est\u00e1 na ponta, usando o sistema, \u00e9 at\u00e9 dif\u00edcil imaginar todo o trabalho que est\u00e1 por traz, feito pelos colegas da \u00e1rea de tecnologia da informa\u00e7\u00e3o\u201d, lembrou.<\/p>\n<hr \/>\n<p><strong>Fonte<\/strong>: R<a href=\"https:\/\/gestao.enat.receita.economia.gov.br\/pt-br\/area_nacional\/areas_interesse\/foruns\/historico\/x-enat\/x-enat-aborda-conversao-de-dados-em-conhecimento\" target=\"_blank\" rel=\"noopener\">eceita Federal (Informe-se &#8211; 23\/10\/2015), via Portal ENAT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 firmado protocolo para distribui\u00e7\u00e3o de vers\u00e3o de ferramenta de Business Intelligence da Receita Federal,<\/p>\n","protected":false},"author":1,"featured_media":10760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,51,83,102],"tags":[],"class_list":["post-8861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auditoria-contabil-tributaria","category-contagil-lite","category-encat","category-fraudes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 firmado protocolo para distribui\u00e7\u00e3o de vers\u00e3o de ferramenta de Business Intelligence da Receita Federal,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Prof. Alexandre Alcantara\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-24T21:00:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T16:44:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"776\" \/>\n\t<meta property=\"og:image:height\" content=\"261\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Editoria: Prof. Alexandre Alcantara\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editoria: Prof. Alexandre Alcantara\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/\"},\"author\":{\"name\":\"Editoria: Prof. Alexandre Alcantara\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/1991ac6c2adfbaedfb22ff57aed2c7db\"},\"headline\":\"X Enat aborda convers\u00e3o de dados em conhecimento\",\"datePublished\":\"2015-10-24T21:00:01+00:00\",\"dateModified\":\"2023-09-28T16:44:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/\"},\"wordCount\":953,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\"},\"image\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-contagil-lite.png\",\"articleSection\":[\"Auditoria Cont\u00e1bil Tribut\u00e1ria\",\"Contagil Lite\",\"ENCAT\",\"Fraude Cont\u00e1bil\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/\",\"name\":\"X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-contagil-lite.png\",\"datePublished\":\"2015-10-24T21:00:01+00:00\",\"dateModified\":\"2023-09-28T16:44:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-contagil-lite.png\",\"contentUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/banner-contagil-lite.png\",\"width\":776,\"height\":261},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/2015\\\/10\\\/24\\\/x-enat-aborda-conversao-de-dados-em-conhecimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"X Enat aborda convers\u00e3o de dados em conhecimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/\",\"name\":\"Prof. Alexandre Alcantara\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/638376dc60edb285cf5914ea02e73975\",\"name\":\"Alexandre Alcantara\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"contentUrl\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\",\"width\":512,\"height\":512,\"caption\":\"Alexandre Alcantara\"},\"logo\":{\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo-quadrada-nova-1.png\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/#\\\/schema\\\/person\\\/1991ac6c2adfbaedfb22ff57aed2c7db\",\"name\":\"Editoria: Prof. Alexandre Alcantara\",\"sameAs\":[\"https:\\\/\\\/alcantara.pro.br\\\/portal\"],\"url\":\"https:\\\/\\\/alcantara.pro.br\\\/portal\\\/author\\\/alexandreportal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/","og_locale":"pt_BR","og_type":"article","og_title":"X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara","og_description":"Ser\u00e1 firmado protocolo para distribui\u00e7\u00e3o de vers\u00e3o de ferramenta de Business Intelligence da Receita Federal,","og_url":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/","og_site_name":"Prof. Alexandre Alcantara","article_published_time":"2015-10-24T21:00:01+00:00","article_modified_time":"2023-09-28T16:44:20+00:00","og_image":[{"width":776,"height":261,"url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png","type":"image\/png"}],"author":"Editoria: Prof. Alexandre Alcantara","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Editoria: Prof. Alexandre Alcantara","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#article","isPartOf":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/"},"author":{"name":"Editoria: Prof. Alexandre Alcantara","@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/1991ac6c2adfbaedfb22ff57aed2c7db"},"headline":"X Enat aborda convers\u00e3o de dados em conhecimento","datePublished":"2015-10-24T21:00:01+00:00","dateModified":"2023-09-28T16:44:20+00:00","mainEntityOfPage":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/"},"wordCount":953,"commentCount":0,"publisher":{"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975"},"image":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#primaryimage"},"thumbnailUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png","articleSection":["Auditoria Cont\u00e1bil Tribut\u00e1ria","Contagil Lite","ENCAT","Fraude Cont\u00e1bil"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/","url":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/","name":"X Enat aborda convers\u00e3o de dados em conhecimento - Prof. Alexandre Alcantara","isPartOf":{"@id":"https:\/\/alcantara.pro.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#primaryimage"},"image":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#primaryimage"},"thumbnailUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png","datePublished":"2015-10-24T21:00:01+00:00","dateModified":"2023-09-28T16:44:20+00:00","breadcrumb":{"@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#primaryimage","url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png","contentUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2021\/08\/banner-contagil-lite.png","width":776,"height":261},{"@type":"BreadcrumbList","@id":"https:\/\/alcantara.pro.br\/portal\/2015\/10\/24\/x-enat-aborda-conversao-de-dados-em-conhecimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/alcantara.pro.br\/portal\/"},{"@type":"ListItem","position":2,"name":"X Enat aborda convers\u00e3o de dados em conhecimento"}]},{"@type":"WebSite","@id":"https:\/\/alcantara.pro.br\/portal\/#website","url":"https:\/\/alcantara.pro.br\/portal\/","name":"Prof. Alexandre Alcantara","description":"","publisher":{"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcantara.pro.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/638376dc60edb285cf5914ea02e73975","name":"Alexandre Alcantara","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","url":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","contentUrl":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png","width":512,"height":512,"caption":"Alexandre Alcantara"},"logo":{"@id":"https:\/\/alcantara.pro.br\/portal\/wp-content\/uploads\/2025\/06\/cropped-logo-quadrada-nova-1.png"}},{"@type":"Person","@id":"https:\/\/alcantara.pro.br\/portal\/#\/schema\/person\/1991ac6c2adfbaedfb22ff57aed2c7db","name":"Editoria: Prof. Alexandre Alcantara","sameAs":["https:\/\/alcantara.pro.br\/portal"],"url":"https:\/\/alcantara.pro.br\/portal\/author\/alexandreportal\/"}]}},"_links":{"self":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/8861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/comments?post=8861"}],"version-history":[{"count":1,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/8861\/revisions"}],"predecessor-version":[{"id":10768,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/posts\/8861\/revisions\/10768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/media\/10760"}],"wp:attachment":[{"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/media?parent=8861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/categories?post=8861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcantara.pro.br\/portal\/wp-json\/wp\/v2\/tags?post=8861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}